{"id":2009,"date":"2020-03-05T17:30:56","date_gmt":"2020-03-05T17:30:56","guid":{"rendered":"http:\/\/stephexstables.com\/riders\/zoe-conter\/"},"modified":"2024-12-17T09:21:03","modified_gmt":"2024-12-17T07:21:03","slug":"zoe-conter","status":"publish","type":"sxrider","link":"https:\/\/stephexstables.com\/fr\/riders\/zoe-conter\/","title":{"rendered":"Zo\u00e9 CONTER"},"content":{"rendered":"\n<p>N\u00e9e dans une famille o\u00f9 les chevaux \u00e9taient au c\u0153ur de la vie quotidienne,\u00a0<strong>Zo\u00e9 Conter<\/strong>, fille a\u00een\u00e9e de <strong>Stephan Conter<\/strong>, a d\u00e9velopp\u00e9 tr\u00e8s t\u00f4t une passion profonde pour le sport. Cette immersion pr\u00e9coce a pav\u00e9 la voie pour son ascension en tant que cavali\u00e8re belge de saut d\u2019obstacles de premier plan sur la sc\u00e8ne mondiale.<\/p>\n\n\n\n<p>Sa carri\u00e8re a rapidement \u00e9t\u00e9 marqu\u00e9e par des r\u00e9alisations significatives, notamment en repr\u00e9sentant la Belgique aux\u00a0<strong>Championnats d\u2019Europe Children<\/strong>\u00a0en\u00a0<strong>2012<\/strong>, puis en tant que Junior en\u00a0<strong>2014<\/strong>,\u00a0<strong>2015<\/strong>\u00a0et <strong>2016<\/strong>. En\u00a0<strong>2016<\/strong>, elle a remport\u00e9 une\u00a0<strong>m\u00e9daille d\u2019argent par \u00e9quipe<\/strong>ainsi qu\u2019une\u00a0<strong>m\u00e9daille de bronze individuelle<\/strong>\u00a0avec son cheval\u00a0<strong>Zeta di Sabuci<\/strong>.<\/p>\n\n\n\n<p>En progressant vers la cat\u00e9gorie Young Riders, Zo\u00e9 a d\u00e9croch\u00e9 une\u00a0<strong>m\u00e9daille d\u2019argent par \u00e9quipe<\/strong>\u00a0aux <strong>Championnats d\u2019Europe 2017<\/strong>\u00a0et a fait ses d\u00e9buts dans la\u00a0<strong>Coupe du Monde FEI<\/strong>\u00a0la m\u00eame ann\u00e9e. Son ascension s\u2019est poursuivie lorsqu\u2019elle a commenc\u00e9 \u00e0 concourir dans des \u00e9preuves\u00a0<strong>CSI5<\/strong>*, en livrant constamment des performances remarquables.<\/p>\n\n\n\n<p>En\u00a0<strong>2019<\/strong>, Zo\u00e9 a remport\u00e9 une victoire notable dans la\u00a0comp\u00e9tition CSI3* 1,45 m \u00e0\u00a0<strong>Sentower Park<\/strong>\u00a0avec sa jument\u00a0<strong><a href=\"https:\/\/stephexstables.com\/sporthorse\/la-una\/\">La Una<\/a><\/strong>, d\u00e9montrant ainsi sa progression constante dans le sport.<\/p>\n\n\n\n<p>Malgr\u00e9 des d\u00e9fis personnels, Zo\u00e9 a fait preuve d\u2019une r\u00e9silience remarquable, revenant sans cesse dans le sport avec une d\u00e9termination renouvel\u00e9e. Son engagement et sa force sont une v\u00e9ritable source d\u2019inspiration, incarnant la conviction que les obstacles peuvent \u00eatre surmont\u00e9s avec pers\u00e9v\u00e9rance.<\/p>\n\n\n\n<p>Actuellement, Zo\u00e9 participe r\u00e9guli\u00e8rement aux niveaux&nbsp;<strong>Grand Prix CSI5<\/strong>* et&nbsp;<strong>Coupe du Monde<\/strong>, consolidant ainsi son statut de figure incontournable du saut d\u2019obstacles international.<\/p>\n","protected":false},"featured_media":7163,"template":"","sxcountry":[409],"class_list":["post-2009","sxrider","type-sxrider","status-publish","has-post-thumbnail","hentry","sxcountry-belgium-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zo\u00e9 CONTER - Stephex Stables<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez le parcours de la cavali\u00e8re belge Zo\u00e9 Conter, de ses premiers succ\u00e8s aux Championnats d\u2019Europe \u00e0 sa place actuelle parmi les meilleures en Grand Prix CSI5* et Coupe du Monde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stephexstables.com\/riders\/zoe-conter\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zo\u00e9 CONTER - Stephex Stables\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez le parcours de la cavali\u00e8re belge Zo\u00e9 Conter, de ses premiers succ\u00e8s aux Championnats d\u2019Europe \u00e0 sa place actuelle parmi les meilleures en Grand Prix CSI5* et Coupe du Monde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stephexstables.com\/riders\/zoe-conter\/\" \/>\n<meta property=\"og:site_name\" content=\"Stephex Stables\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-17T07:21:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stephexstables.com\/wp-content\/uploads\/2020\/03\/WEF4THURZC-15-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stephexstables.com\\\/riders\\\/zoe-conter\\\/\",\"url\":\"https:\\\/\\\/stephexstables.com\\\/riders\\\/zoe-conter\\\/\",\"name\":\"Zo\u00e9 CONTER - Stephex Stables\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stephexstables.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stephexstables.com\\\/riders\\\/zoe-conter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stephexstables.com\\\/riders\\\/zoe-conter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stephexstables.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/WEF4THURZC-15-scaled.jpg\",\"datePublished\":\"2020-03-05T17:30:56+00:00\",\"dateModified\":\"2024-12-17T07:21:03+00:00\",\"description\":\"D\u00e9couvrez le parcours de la cavali\u00e8re belge Zo\u00e9 Conter, de ses premiers succ\u00e8s aux Championnats d\u2019Europe \u00e0 sa place actuelle parmi les meilleures en Grand Prix CSI5* et Coupe du Monde.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stephexstables.com\\\/riders\\\/zoe-conter\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stephexstables.com\\\/riders\\\/zoe-conter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stephexstables.com\\\/riders\\\/zoe-conter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stephexstables.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/WEF4THURZC-15-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/stephexstables.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/WEF4THURZC-15-scaled.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"Zo\u00e9 Conter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stephexstables.com\\\/riders\\\/zoe-conter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stephexstables.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zo\u00e9 CONTER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stephexstables.com\\\/#website\",\"url\":\"https:\\\/\\\/stephexstables.com\\\/\",\"name\":\"Stephex Stables\",\"description\":\"Stephex Success Stories\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stephexstables.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zo\u00e9 CONTER - Stephex Stables","description":"D\u00e9couvrez le parcours de la cavali\u00e8re belge Zo\u00e9 Conter, de ses premiers succ\u00e8s aux Championnats d\u2019Europe \u00e0 sa place actuelle parmi les meilleures en Grand Prix CSI5* et Coupe du Monde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stephexstables.com\/riders\/zoe-conter\/","og_locale":"fr_FR","og_type":"article","og_title":"Zo\u00e9 CONTER - Stephex Stables","og_description":"D\u00e9couvrez le parcours de la cavali\u00e8re belge Zo\u00e9 Conter, de ses premiers succ\u00e8s aux Championnats d\u2019Europe \u00e0 sa place actuelle parmi les meilleures en Grand Prix CSI5* et Coupe du Monde.","og_url":"https:\/\/stephexstables.com\/riders\/zoe-conter\/","og_site_name":"Stephex Stables","article_modified_time":"2024-12-17T07:21:03+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/stephexstables.com\/wp-content\/uploads\/2020\/03\/WEF4THURZC-15-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stephexstables.com\/riders\/zoe-conter\/","url":"https:\/\/stephexstables.com\/riders\/zoe-conter\/","name":"Zo\u00e9 CONTER - Stephex Stables","isPartOf":{"@id":"https:\/\/stephexstables.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stephexstables.com\/riders\/zoe-conter\/#primaryimage"},"image":{"@id":"https:\/\/stephexstables.com\/riders\/zoe-conter\/#primaryimage"},"thumbnailUrl":"https:\/\/stephexstables.com\/wp-content\/uploads\/2020\/03\/WEF4THURZC-15-scaled.jpg","datePublished":"2020-03-05T17:30:56+00:00","dateModified":"2024-12-17T07:21:03+00:00","description":"D\u00e9couvrez le parcours de la cavali\u00e8re belge Zo\u00e9 Conter, de ses premiers succ\u00e8s aux Championnats d\u2019Europe \u00e0 sa place actuelle parmi les meilleures en Grand Prix CSI5* et Coupe du Monde.","breadcrumb":{"@id":"https:\/\/stephexstables.com\/riders\/zoe-conter\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stephexstables.com\/riders\/zoe-conter\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stephexstables.com\/riders\/zoe-conter\/#primaryimage","url":"https:\/\/stephexstables.com\/wp-content\/uploads\/2020\/03\/WEF4THURZC-15-scaled.jpg","contentUrl":"https:\/\/stephexstables.com\/wp-content\/uploads\/2020\/03\/WEF4THURZC-15-scaled.jpg","width":1707,"height":2560,"caption":"Zo\u00e9 Conter"},{"@type":"BreadcrumbList","@id":"https:\/\/stephexstables.com\/riders\/zoe-conter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stephexstables.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Zo\u00e9 CONTER"}]},{"@type":"WebSite","@id":"https:\/\/stephexstables.com\/#website","url":"https:\/\/stephexstables.com\/","name":"Stephex Stables","description":"Stephex Success Stories","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stephexstables.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/stephexstables.com\/fr\/wp-json\/wp\/v2\/sxrider\/2009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stephexstables.com\/fr\/wp-json\/wp\/v2\/sxrider"}],"about":[{"href":"https:\/\/stephexstables.com\/fr\/wp-json\/wp\/v2\/types\/sxrider"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stephexstables.com\/fr\/wp-json\/wp\/v2\/media\/7163"}],"wp:attachment":[{"href":"https:\/\/stephexstables.com\/fr\/wp-json\/wp\/v2\/media?parent=2009"}],"wp:term":[{"taxonomy":"sxcountry","embeddable":true,"href":"https:\/\/stephexstables.com\/fr\/wp-json\/wp\/v2\/sxcountry?post=2009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}